{"id":287,"date":"2013-06-01T22:23:39","date_gmt":"2013-06-01T21:23:39","guid":{"rendered":"http:\/\/pop-culture.fr\/blog\/?p=287"},"modified":"2013-06-01T22:26:46","modified_gmt":"2013-06-01T21:26:46","slug":"du-nouveau-pour-borderlands-2","status":"publish","type":"post","link":"https:\/\/pop-culture.fr\/blog\/du-nouveau-pour-borderlands-2\/","title":{"rendered":"Du nouveau pour Borderlands 2"},"content":{"rendered":"<p>Si vous me lisez un tant soit peu r\u00e9guli\u00e8rement, vous n&rsquo;\u00eates pas sans savoir que je suis un grand fan de <strong>Borderlands 2<\/strong> (ainsi que du premier opus). Le jeu caracole en t\u00eate des jeux les plus jou\u00e9s de ma biblioth\u00e8que steam, avec plus de 250 heurs au compteur&#8230; et je m&rsquo;en lasse \u00e0 peine. Les DLC ont \u00e9t\u00e9, dans les grandes lignes, de tr\u00e8s bonne facture, apportant ce qu&rsquo;il fallait de renouveau et de challenge.<\/p>\n<p>Cependant, m\u00eame si <em>Borderlands 2<\/em> reste de l&rsquo;excellent <em>Borderlands<\/em>, il devenait difficile de surprendre les vieux fans, blas\u00e9s par des massacres sans fin, de l&rsquo;humour potache et noir \u00e0 outrance et des situations absurdes que les Monthy Pythons ne renieraient pas. Cel\u00e0 pourrait bien changer avec le futur DLC, qui devrait \u00e9galement \u00eatre le dernier :\u00a0<strong>Tiny Tina&rsquo;s Assault on Dragon Keep !<\/strong><\/p>\n<p><a href=\"https:\/\/pop-culture.fr\/blog\/wp-content\/uploads\/2013\/06\/Tiny-Tina-s-Assault-on-Dragon-Keep-DLC-for-Borderlands-2-Gets-Artwork.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-289\" alt=\"Tiny Tina\" src=\"https:\/\/pop-culture.fr\/blog\/wp-content\/uploads\/2013\/06\/Tiny-Tina-s-Assault-on-Dragon-Keep-DLC-for-Borderlands-2-Gets-Artwork-300x164.jpg\" width=\"300\" height=\"164\" srcset=\"https:\/\/pop-culture.fr\/blog\/wp-content\/uploads\/2013\/06\/Tiny-Tina-s-Assault-on-Dragon-Keep-DLC-for-Borderlands-2-Gets-Artwork-300x164.jpg 300w, https:\/\/pop-culture.fr\/blog\/wp-content\/uploads\/2013\/06\/Tiny-Tina-s-Assault-on-Dragon-Keep-DLC-for-Borderlands-2-Gets-Artwork-500x274.jpg 500w, https:\/\/pop-culture.fr\/blog\/wp-content\/uploads\/2013\/06\/Tiny-Tina-s-Assault-on-Dragon-Keep-DLC-for-Borderlands-2-Gets-Artwork.jpg 728w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><!--more--><\/p>\n<p>Je ne vais pas vous faire tout en blabla sur ce futur addon, je vais plut\u00f4t vous envoyer lire <a href=\"http:\/\/www.jeuxvideo.com\/articles\/0001\/00018445-borderlands-2-tiny-tina-s-assault-on-dragon-keep-preview.htm\" target=\"_blank\">l&rsquo;aper\u00e7u de jeuxvideo.com<\/a> ou, si l&rsquo;Anglois ne vous h\u00e9risse pas trop, vers l&rsquo;un des articles list\u00e9s <a href=\"http:\/\/www.gearboxsoftware.com\/community\/articles\/1043\/tiny-tina-s-assault-on-dragon-keep-previews\" target=\"_blank\">ici<\/a>.<\/p>\n<p>Et, comme j&rsquo;aime vous g\u00e2ter, je vais encha\u00eener avec cette tr\u00e8s chouette vid\u00e9o de 20 minutes :<\/p>\n<p><iframe loading=\"lazy\" src=\"http:\/\/www.youtube.com\/embed\/3-WJEC3VfhE\" height=\"315\" width=\"560\" allowfullscreen=\"\" frameborder=\"0\"><\/iframe><\/p>\n<p>Vous l&rsquo;aurez compris, on va encore plus loin dans le n&rsquo;importe quoi que d&rsquo;habitude et, franchement, j&rsquo;ai vraiment h\u00e2te ! Ils connaissent leur public, les bougres, en tout cas la portion dont je suis un membre repr\u00e9sentatif : les trentenaires \u00e9lev\u00e9s au JDR, <em>D&amp;D<\/em> notamment. Les (seuls) vrais geeks, en somme (:P).<\/p>\n<p>Comme en plus Gearbox semble partant pour nous pondre quelques m\u00e9canismes narratifs originaux et un challenge bien relev\u00e9, je suis d&rsquo;autant plus impatient ! En attendant, je vous propose de visionner cette belle vid\u00e9o mettant en sc\u00e8ne <strong>Krieg le Psycho<\/strong>, l&rsquo;autre annonce du moment pour le jeu. C&rsquo;est vraiment excellent de bout en bout, 100% <em>Borderlands<\/em> ! Enjoy!<\/p>\n<p><iframe loading=\"lazy\" src=\"http:\/\/www.youtube.com\/embed\/h3mhWvWEb9g\" height=\"315\" width=\"560\" allowfullscreen=\"\" frameborder=\"0\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si vous me lisez un tant soit peu r\u00e9guli\u00e8rement, vous n&rsquo;\u00eates pas sans savoir que je suis un grand fan de Borderlands 2 (ainsi que du premier opus). Le jeu caracole en t\u00eate des jeux les plus jou\u00e9s de ma biblioth\u00e8que steam, avec plus de 250 heurs au compteur&#8230; et je m&rsquo;en lasse \u00e0 peine. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[82],"tags":[11,115,102,114,55],"acf":[],"_links":{"self":[{"href":"https:\/\/pop-culture.fr\/blog\/wp-json\/wp\/v2\/posts\/287"}],"collection":[{"href":"https:\/\/pop-culture.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pop-culture.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pop-culture.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pop-culture.fr\/blog\/wp-json\/wp\/v2\/comments?post=287"}],"version-history":[{"count":5,"href":"https:\/\/pop-culture.fr\/blog\/wp-json\/wp\/v2\/posts\/287\/revisions"}],"predecessor-version":[{"id":292,"href":"https:\/\/pop-culture.fr\/blog\/wp-json\/wp\/v2\/posts\/287\/revisions\/292"}],"wp:attachment":[{"href":"https:\/\/pop-culture.fr\/blog\/wp-json\/wp\/v2\/media?parent=287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pop-culture.fr\/blog\/wp-json\/wp\/v2\/categories?post=287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pop-culture.fr\/blog\/wp-json\/wp\/v2\/tags?post=287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}